{"id":2513,"date":"2021-12-14T10:35:43","date_gmt":"2021-12-14T10:35:43","guid":{"rendered":"https:\/\/fuecapilar.com\/fr\/?p=4305"},"modified":"2023-09-12T14:42:05","modified_gmt":"2023-09-12T14:42:05","slug":"alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux","status":"publish","type":"post","link":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/","title":{"rendered":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Pour comprendre ce qu&rsquo;est DUPA, nous devons d&rsquo;abord comprendre ce qu&rsquo;est la calvitie masculine.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">La calvitie masculine est \u00e9galement connue sous le nom d&rsquo;alop\u00e9cie androg\u00e9n\u00e9tique ou alop\u00e9cie androg\u00e9nique. Elle se caract\u00e9rise par une perte de cheveux au niveau des golfes, de la partie frontale et de la partie sup\u00e9rieure du cuir chevelu. Elle survient chez les hommes qui sont g\u00e9n\u00e9tiquement pr\u00e9dispos\u00e9s \u00e0 \u00eatre plus sensibles aux effets de l&rsquo;hormone DHT, et cette condition peut \u00eatre h\u00e9rit\u00e9e de chaque c\u00f4t\u00e9 de la famille.<br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">L\u2019homme produit de la DHT (Dihydrotestost\u00e9rone), un sous-produit de la testost\u00e9rone par l&rsquo;interm\u00e9diaire de l&rsquo;enzyme 5-alpha-r\u00e9ductase. Cette enzyme est celle qui transforme un certain pourcentage de testost\u00e9rone qui se trouve dans les tissus tels que la peau, le foie, la prostate et les follicules. Si le patient est g\u00e9n\u00e9tiquement sensible \u00e0 la chute de cheveux, la DHT peut rejoindre les r\u00e9cepteurs folliculaires et les faire diminuer, s&rsquo;affaiblir et finalement mourir. Ce processus a pour r\u00e9sultat de provoquer la fin de la croissance des follicules touch\u00e9s.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Sachant que la calvitie masculine peut \u00eatre cat\u00e9goris\u00e9e par l&rsquo;\u00e9chelle de Norwood-Hamilton, qui la d\u00e9finit en sept stades de calvitie avec des mod\u00e8les diff\u00e9rents pour chacun, il faut comprendre que DUPA est un sous-type de chute de cheveux h\u00e9r\u00e9ditaire et que cette cat\u00e9gorisation ne s&rsquo;applique pas \u00e0 tous les hommes souffrant de la perte de cheveux. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 500;\"><br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3126-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"3126\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/2513#wpcf7-f3126-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3126\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3126-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-post\">\n\t<div class=\"form-post-titulo\">\n\t\t<p>Je souhaite recevoir plus d'informations\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-post-campos\">\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-boton\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"clear\">\n\t<\/div>\n\t<div class=\"form-post-politica\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-498\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-498\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p>j'ai lu le <a href=\"https:\/\/www.fuecapilar.com\/privacy-policy\/\">politique de confidentialit\u00e9<\/a>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n<\/span><\/p>\n<h2><span style=\"font-weight: 500;\"><br \/>\n<\/span><b>QU&rsquo;EST-CE QUE DUPA ?<\/b><b><br \/>\n<\/b><b><\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Pour comprendre ce type d&rsquo;alop\u00e9cie, nous devons conna\u00eetre les diff\u00e9rences entre l&rsquo;alop\u00e9cie diffuse (DPA) et l&rsquo;alop\u00e9cie diffuse non structur\u00e9e (DUPA); Cependant, les deux sont des sous-types de perte de cheveux h\u00e9r\u00e9ditaire. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">L&rsquo;alop\u00e9cie diffuse (DPA) se caract\u00e9rise par un amincissement de la partie sup\u00e9rieure du cuir chevelu, en commen\u00e7ant de la partie frontale jusqu&rsquo; \u00e0 la couronne, tandis que la partie arri\u00e8re et les c\u00f4t\u00e9s ne sont pas affect\u00e9s. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Pour l&rsquo;alop\u00e9cie diffuse non structur\u00e9e (DUPA), le motif affecte non seulement la zone frontale et la couronne, mais \u00e9galement les c\u00f4t\u00e9s et l&rsquo;arri\u00e8re, provoquant un amincissement, une faiblesse, une s\u00e9cheresse, une chute et par cons\u00e9quent une perte en densit\u00e9.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">DUPA est diagnostiqu\u00e9 en recherchant une miniaturisation ou des changements dans le diam\u00e8tre du cheveux. Cela peut \u00eatre difficile \u00e0 d\u00e9tecter chez les jeunes patients car ce sch\u00e9ma d&rsquo;amincissement n&rsquo;appara\u00eet clairement qu&rsquo;\u00e0 la fin de la vingtaine.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les sympt\u00f4mes sont un amincissement rapide et g\u00e9n\u00e9ralis\u00e9 des cheveux sur la zone frontale, la couronne, les c\u00f4t\u00e9s et l&rsquo;arri\u00e8re de la t\u00eate.<\/span><span style=\"font-weight: 400;\"><\/p>\n<p><\/span><span style=\"font-weight: 400;\">Les cheveux commencent \u00e0 se miniaturiser et ressemblent \u00e0 des m\u00e8ches laissant appara\u00eetre le cuir chevelu par dessous, mais normalement ils ne tombent pas directement. Il commence \u00e0 s&rsquo;amincir et, selon les patients, tombe plus lentement ou plus vite.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>DUPA ET TRAITEMENT M\u00c9DICAL <\/b><b><br \/>\n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Le finast\u00e9ride et le minoxidil sont connus pour \u00eatre efficaces pour tout type d&rsquo;alop\u00e9cie androg\u00e9nique ; le Finast\u00e9ride bloque l&rsquo;hormone DHT, stoppant la chute des cheveux et parfois m\u00eame les \u00e9paississant, et le Minoxidil envoie plus de sang aux follicules, leur apportant une nutrition.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Cette combinaison de m\u00e9dicaments donne des r\u00e9sultats apr\u00e8s au moins 6 mois d&rsquo;utilisation. Le pic de son efficacit\u00e9 n&rsquo;est qu&rsquo;apr\u00e8s 18-24 mois d&rsquo;utilisation.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Le finast\u00e9ride est un traitement hormonal ; par cons\u00e9quent, il doit \u00eatre g\u00e9r\u00e9 progressivement. Le corps a besoin de traiter et d&rsquo;assimiler ce m\u00e9dicament. Certains patients peuvent ressentir des effets secondaires lorsqu&rsquo;ils commencent imm\u00e9diatement ce traitement avec 1 mg par jour.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Nous avons d\u00e9tect\u00e9 que ces effets secondaires sont moins observ\u00e9s chez beaucoup de nos patients qui commencent avec une dose plus faible par la suite l&rsquo;augmentant progressivement mois apr\u00e8s mois. Dans ces conditions, moins de 3% des patients ressentent ces effets secondaires.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Le minoxidil est un m\u00e9dicament vasodilatateur, couramment utilis\u00e9 pour l&rsquo;hypertension art\u00e9rielle et la perte de cheveux. Il se pr\u00e9sente sous forme de comprim\u00e9s, de solution topique sous forme liquide ou mousse. Ces options peuvent \u00eatre appliqu\u00e9es avant d&rsquo;aller dormir ou si aucun produit coiffant ne doit \u00eatre utilis\u00e9 apr\u00e8s. Ce m\u00e9dicament produit un \u00e9largissement des vaisseaux sanguins et l&rsquo;ouverture des canaux potassiques, permettant plus de sang, de nutriments et d&rsquo;oxyg\u00e8ne aux follicules. Il est tout \u00e0 fait normal d&rsquo;avoir une chute au d\u00e9but du traitement car les cheveux doivent \u00eatre r\u00e9nov\u00e9s pour repousser avec plus de force.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>DUPA ET GREFFE DE CHEVEUX<\/b> <b><br \/>\n<\/b><b><\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Dans la plupart des cas, un patient qui a \u00e9t\u00e9 diagnostiqu\u00e9 avec DUPA ne sera pas un candidat \u00e9ligible pour une greffe de cheveux. Comme mentionn\u00e9 ci-dessus, DUPA provoque un amincissement global de nos cheveux, y compris les cheveux de la zone donneuse.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">En raison de cet amincissement, notre zone donneuse n&rsquo;est pas consid\u00e9r\u00e9e comme une zone s\u00e9curis\u00e9e. Les greffons \u00e0 extraire de la zone donneuse et \u00e0 implanter dans l&rsquo;une des zones de calvitie de la zone receveuse sont susceptibles de tomber car ils peuvent \u00eatre affect\u00e9s par l&rsquo;hormone DHT.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Suis-je donc condamn\u00e9 si je souffre de DUPA ? Nous avons vu des patients qui ont tr\u00e8s bien r\u00e9pondu aux traitements m\u00e9dicamenteux (finast\u00e9ride\/dutast\u00e9ride et minoxidil) apr\u00e8s 12 \u00e0 18 mois. Au bout de ce d\u00e9lai, non seulement la progression de l&rsquo;amincissement s&rsquo;est arr\u00eat\u00e9e mais il y a \u00e9galement eu une reprise en densit\u00e9.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Dans certains cas, ces patients deviennent \u00e9ligible pour une greffe de cheveux. Il convient de noter que les patients devront continuer \u00e0 utiliser ces m\u00e9dicaments sans aucune interruption apr\u00e8s la greffe de cheveux ; sinon, ces greffons implant\u00e9s risquent de tomber dans l&rsquo;absence de ces m\u00e9dicaments.<\/p>\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3126-o2\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"3126\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/2513#wpcf7-f3126-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3126\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3126-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-post\">\n\t<div class=\"form-post-titulo\">\n\t\t<p>Je souhaite recevoir plus d'informations\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-post-campos\">\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-campo\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-post-boton\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"clear\">\n\t<\/div>\n\t<div class=\"form-post-politica\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-498\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-498\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p>j'ai lu le <a href=\"https:\/\/www.fuecapilar.com\/privacy-policy\/\">politique de confidentialit\u00e9<\/a>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n<\/span><\/p>\n<h3><b><br \/>\n<\/b><b>Quelle technique d&rsquo;extraction serait la plus recommand\u00e9e si je souffre de DUPA ?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Tout en acceptant les limitations en termes de succ\u00e8s pour un patient atteint d&rsquo;une alop\u00e9cie de type DUPA, envisageant de subir une greffe de cheveux apr\u00e8s avoir utilis\u00e9 les m\u00e9dicaments recommand\u00e9s, la technique d&rsquo;extraction FUE (Follicular Unit Extraction) serait plus conseill\u00e9 que la technique FUT (strip chirurgie).<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Il est pr\u00e9f\u00e9rable lors de l&rsquo;extraction FUE que nous puissions identifier les zones les moins affect\u00e9es par l&rsquo;amincissement tout en recherchant les greffons disponibles les plus sains.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Si nous utilisons la technique FUT comme m\u00e9thode d&rsquo;extraction en raison de son avantage au niveau du rendement sup\u00e9rieure en termes de nombre de greffons par cm\u00b2, cela ne serait pas applicable aux patients souffrant de DUPA, car l&rsquo;amincissement est pr\u00e9sent dans toute la zone s\u00e9curis\u00e9e.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">En r\u00e9alit\u00e9, un diagnostic pr\u00e9coce et pr\u00e9cis de la maladie suivi d&rsquo;un traitement m\u00e9dical appropri\u00e9 sera primordial lors de la planification d&rsquo;une greffe de cheveux. Dans ce cas de figure, le suivi r\u00e9gulier d&rsquo;un dermatologue ou d&rsquo;un trichologue sera recommand\u00e9 afin d&rsquo;obtenir un bon r\u00e9sultat.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour comprendre ce qu&rsquo;est DUPA, nous devons d&rsquo;abord comprendre ce qu&rsquo;est la calvitie masculine. La calvitie masculine est \u00e9galement connue sous le nom d&rsquo;alop\u00e9cie androg\u00e9n\u00e9tique ou alop\u00e9cie androg\u00e9nique. Elle se caract\u00e9rise par une perte de cheveux au niveau des golfes, de la partie frontale et de la partie sup\u00e9rieure du cuir chevelu. Elle survient chez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[13],"tags":[],"class_list":["post-2513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR\" \/>\n<meta property=\"og:description\" content=\"Pour comprendre ce qu&rsquo;est DUPA, nous devons d&rsquo;abord comprendre ce qu&rsquo;est la calvitie masculine. La calvitie masculine est \u00e9galement connue sous le nom d&rsquo;alop\u00e9cie androg\u00e9n\u00e9tique ou alop\u00e9cie androg\u00e9nique. Elle se caract\u00e9rise par une perte de cheveux au niveau des golfes, de la partie frontale et de la partie sup\u00e9rieure du cuir chevelu. Elle survient chez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/\" \/>\n<meta property=\"og:site_name\" content=\"FUECAPILAR\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T10:35:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T14:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fuecapilar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fuecapilar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/\"},\"author\":{\"name\":\"fuecapilar\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#\\\/schema\\\/person\\\/76e22a8dbc23e73c56c4e753c31c3b95\"},\"headline\":\"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux\",\"datePublished\":\"2021-12-14T10:35:43+00:00\",\"dateModified\":\"2023-09-12T14:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/\"},\"wordCount\":1245,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Paciente-estres.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/\",\"url\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/\",\"name\":\"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Paciente-estres.jpg\",\"datePublished\":\"2021-12-14T10:35:43+00:00\",\"dateModified\":\"2023-09-12T14:42:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Paciente-estres.jpg\",\"contentUrl\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Paciente-estres.jpg\",\"width\":400,\"height\":267},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#website\",\"url\":\"https:\\\/\\\/fuecapilar.com\\\/\",\"name\":\"FUECAPILAR\",\"description\":\"Surgery performed by a surgeon\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuecapilar.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#organization\",\"name\":\"FUECAPILAR\",\"url\":\"https:\\\/\\\/fuecapilar.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/fuecapilar-logo.png\",\"contentUrl\":\"https:\\\/\\\/fuecapilar.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/fuecapilar-logo.png\",\"width\":400,\"height\":85,\"caption\":\"FUECAPILAR\"},\"image\":{\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuecapilar.com\\\/#\\\/schema\\\/person\\\/76e22a8dbc23e73c56c4e753c31c3b95\",\"name\":\"fuecapilar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g\",\"caption\":\"fuecapilar\"},\"url\":\"https:\\\/\\\/fuecapilar.com\\\/fr\\\/author\\\/fuecapilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/","og_locale":"fr_FR","og_type":"article","og_title":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR","og_description":"Pour comprendre ce qu&rsquo;est DUPA, nous devons d&rsquo;abord comprendre ce qu&rsquo;est la calvitie masculine. La calvitie masculine est \u00e9galement connue sous le nom d&rsquo;alop\u00e9cie androg\u00e9n\u00e9tique ou alop\u00e9cie androg\u00e9nique. Elle se caract\u00e9rise par une perte de cheveux au niveau des golfes, de la partie frontale et de la partie sup\u00e9rieure du cuir chevelu. Elle survient chez [&hellip;]","og_url":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/","og_site_name":"FUECAPILAR","article_published_time":"2021-12-14T10:35:43+00:00","article_modified_time":"2023-09-12T14:42:05+00:00","og_image":[{"width":400,"height":267,"url":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg","type":"image\/jpeg"}],"author":"fuecapilar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fuecapilar","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#article","isPartOf":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/"},"author":{"name":"fuecapilar","@id":"https:\/\/fuecapilar.com\/#\/schema\/person\/76e22a8dbc23e73c56c4e753c31c3b95"},"headline":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux","datePublished":"2021-12-14T10:35:43+00:00","dateModified":"2023-09-12T14:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/"},"wordCount":1245,"commentCount":0,"publisher":{"@id":"https:\/\/fuecapilar.com\/#organization"},"image":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#primaryimage"},"thumbnailUrl":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/","url":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/","name":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux - FUECAPILAR","isPartOf":{"@id":"https:\/\/fuecapilar.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#primaryimage"},"image":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#primaryimage"},"thumbnailUrl":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg","datePublished":"2021-12-14T10:35:43+00:00","dateModified":"2023-09-12T14:42:05+00:00","breadcrumb":{"@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#primaryimage","url":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg","contentUrl":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2019\/09\/Paciente-estres.jpg","width":400,"height":267},{"@type":"BreadcrumbList","@id":"https:\/\/fuecapilar.com\/fr\/alopecie-diffuse-non-structuree-dupa-et-greffe-cheveux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fuecapilar.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Alop\u00e9cie diffuse non structur\u00e9e (DUPA) et greffe de cheveux"}]},{"@type":"WebSite","@id":"https:\/\/fuecapilar.com\/#website","url":"https:\/\/fuecapilar.com\/","name":"FUECAPILAR","description":"Surgery performed by a surgeon","publisher":{"@id":"https:\/\/fuecapilar.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuecapilar.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fuecapilar.com\/#organization","name":"FUECAPILAR","url":"https:\/\/fuecapilar.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fuecapilar.com\/#\/schema\/logo\/image\/","url":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2023\/04\/fuecapilar-logo.png","contentUrl":"https:\/\/fuecapilar.com\/wp-content\/uploads\/2023\/04\/fuecapilar-logo.png","width":400,"height":85,"caption":"FUECAPILAR"},"image":{"@id":"https:\/\/fuecapilar.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fuecapilar.com\/#\/schema\/person\/76e22a8dbc23e73c56c4e753c31c3b95","name":"fuecapilar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/951a14ccd73caa77e3dbef5ef02f3eaebe8c9a193f5c7f80c0479a7b876d8440?s=96&d=mm&r=g","caption":"fuecapilar"},"url":"https:\/\/fuecapilar.com\/fr\/author\/fuecapilar\/"}]}},"_links":{"self":[{"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/posts\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":2,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/posts\/2513\/revisions"}],"predecessor-version":[{"id":3129,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/posts\/2513\/revisions\/3129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/media\/2449"}],"wp:attachment":[{"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/categories?post=2513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuecapilar.com\/fr\/wp-json\/wp\/v2\/tags?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}